{"id":19304,"date":"2025-06-26T10:14:21","date_gmt":"2025-06-26T13:14:21","guid":{"rendered":"https:\/\/www.jornalponto.com\/site\/?p=19304"},"modified":"2025-06-26T10:14:24","modified_gmt":"2025-06-26T13:14:24","slug":"pinheiral-pode-receber-unidade-do-corpo-de-bombeiros","status":"publish","type":"post","link":"https:\/\/www.jornalponto.com\/site\/2025\/06\/26\/pinheiral-pode-receber-unidade-do-corpo-de-bombeiros\/","title":{"rendered":"Pinheiral pode receber unidade do Corpo de Bombeiros"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img alt=\"\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2025\/06\/bombeiros-pinheiral-1024x768.jpg\" alt=\"\" class=\"wp-image-19305\" style=\"width:681px;height:auto\" srcset=\"https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2025\/06\/bombeiros-pinheiral-1024x768.jpg 1024w, https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2025\/06\/bombeiros-pinheiral-300x225.jpg 300w, https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2025\/06\/bombeiros-pinheiral-768x576.jpg 768w, https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2025\/06\/bombeiros-pinheiral-1536x1152.jpg 1536w, https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2025\/06\/bombeiros-pinheiral-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Defesa Civil de Pinheiral realiza visita t\u00e9cnica com equipe especializada para avalia\u00e7\u00e3o final de \u00e1rea destinada ao Corpo de Bombeiros<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">A Defesa Civil de Pinheiral recebeu, nesta ter\u00e7a-feira, 24, uma comitiva t\u00e9cnica do Corpo de Bombeiros Militar do Estado do Rio de Janeiro (CBMERJ) e da Defesa Civil Estadual para uma visita de avalia\u00e7\u00e3o ao local proposto para a instala\u00e7\u00e3o de uma unidade no munic\u00edpio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A visita teve car\u00e1ter t\u00e9cnico e decisivo, com foco na an\u00e1lise estrutural e estrat\u00e9gica da \u00e1rea estudada. A equipe avaliou criteriosamente as condi\u00e7\u00f5es do terreno, acessibilidade, infraestrutura existente e viabilidade operacional da implanta\u00e7\u00e3o da nova unidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Participaram da a\u00e7\u00e3o o coordenador da REDEC Sul I, Major Diego; o Tenente-Coronel Marcelo Abreu, da Defesa Civil Estadual; o Major Leonardo Trancoso, representando o CBMERJ; o diretor da Defesa Civil de Pinheiral, Alan Gentil; o chefe da Divis\u00e3o de Ordem P\u00fablica, Marcelo; al\u00e9m dos secret\u00e1rios municipais M\u00e1rcio Pires (Obras), F\u00e1bio Nogueira (Ambiente), Jailson Rodrigues (Servi\u00e7os P\u00fablicos e vice-prefeito do munic\u00edpio), e o engenheiro civil Rodrigo Blazutti, que atuou como representante t\u00e9cnico da Prefeitura, contribuindo com an\u00e1lises e pareceres fundamentais para o avan\u00e7o do projeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em fevereiro, com articula\u00e7\u00e3o do deputado estadual e secret\u00e1rio de Turismo, Gustavo Tutuca, Pinheiral avan\u00e7ou nesta demanda. Em reuni\u00e3o realizada na capital, o secret\u00e1rio municipal de Ordem P\u00fablica, Defesa Civil e Fiscaliza\u00e7\u00e3o, Anderson Costa Alonso, junto com o diretor de Defesa Civil, Alan FIlipe, se reuniram com o subsecret\u00e1rio estadual de Defesa Civil, Coronel Lauro Botto. As negocia\u00e7\u00f5es est\u00e3o avan\u00e7adas e, em breve, o munic\u00edpio ter\u00e1 seu pr\u00f3prio destacamento do Corpo de Bombeiros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Defesa Civil de Pinheiral realiza visita t\u00e9cnica com equipe especializada para avalia\u00e7\u00e3o final de \u00e1rea destinada ao Corpo de Bombeiros A Defesa Civil de Pinheiral recebeu, nesta ter\u00e7a-feira, 24, uma comitiva t\u00e9cnica do Corpo de Bombeiros Militar do Estado do Rio de Janeiro (CBMERJ) e da Defesa Civil Estadual para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19305,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[69,32,36],"tags":[],"class_list":["post-19304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-destaque","category-pinheiral"],"_links":{"self":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/19304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/comments?post=19304"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/19304\/revisions"}],"predecessor-version":[{"id":19306,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/19304\/revisions\/19306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/media\/19305"}],"wp:attachment":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/media?parent=19304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/categories?post=19304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/tags?post=19304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}