{"id":21249,"date":"2025-08-29T08:34:03","date_gmt":"2025-08-29T11:34:03","guid":{"rendered":"https:\/\/www.jornalponto.com\/site\/?p=21249"},"modified":"2025-08-29T08:34:04","modified_gmt":"2025-08-29T11:34:04","slug":"prf-prende-homem-com-documentos-falsificados-durante-fiscalizacao-em-pirai","status":"publish","type":"post","link":"https:\/\/www.jornalponto.com\/site\/2025\/08\/29\/prf-prende-homem-com-documentos-falsificados-durante-fiscalizacao-em-pirai\/","title":{"rendered":"PRF prende homem com documentos falsificados durante fiscaliza\u00e7\u00e3o em Pira\u00ed"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Uma fiscaliza\u00e7\u00e3o de rotina realizada pela Pol\u00edcia Rodovi\u00e1ria Federal resultou na pris\u00e3o de um homem de 53 anos, na tarde de quarta-feira (28), na Via Dutra, em Pira\u00ed. A ocorr\u00eancia aconteceu por volta das 14h20, no km 233, em frente \u00e0 Unidade Operacional da PRF em Cai\u00e7ara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a corpora\u00e7\u00e3o, os agentes abordaram um ve\u00edculo Fiat Pulse, com placas de Belo Horizonte (MG), ocupado por tr\u00eas pessoas \u2014 a motorista e dois passageiros. Durante a entrevista, os ocupantes apresentaram respostas contradit\u00f3rias sobre o motivo da viagem, o que levantou suspeita dos policiais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na revista ao interior do carro, os agentes encontraram diversos documentos nos pertences de um dos passageiros. Segundo a PRF, havia fortes ind\u00edcios de falsifica\u00e7\u00e3o. Questionado, o homem admitiu ter adquirido os documentos em S\u00e3o Paulo, com a inten\u00e7\u00e3o de utiliz\u00e1-los para abrir contas banc\u00e1rias e emitir cart\u00f5es de cr\u00e9dito em nome de terceiros, a fim de gastar os limites dispon\u00edveis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diante da situa\u00e7\u00e3o, ele recebeu voz de pris\u00e3o em flagrante e foi encaminhado para a Delegacia da Pol\u00edcia Federal em Volta Redonda, onde o caso foi registrado e segue sob investiga\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma fiscaliza\u00e7\u00e3o de rotina realizada pela Pol\u00edcia Rodovi\u00e1ria Federal resultou na pris\u00e3o de um homem de 53 anos, na tarde de quarta-feira (28), na Via Dutra, em Pira\u00ed. A ocorr\u00eancia aconteceu por volta das 14h20, no km 233, em frente \u00e0 Unidade Operacional da PRF em Cai\u00e7ara. De acordo com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9682,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[37,53],"tags":[],"class_list":["post-21249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pirai","category-policia"],"_links":{"self":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/21249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/comments?post=21249"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/21249\/revisions"}],"predecessor-version":[{"id":21250,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/21249\/revisions\/21250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/media\/9682"}],"wp:attachment":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/media?parent=21249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/categories?post=21249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/tags?post=21249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}