{"id":21251,"date":"2025-08-29T08:51:37","date_gmt":"2025-08-29T11:51:37","guid":{"rendered":"https:\/\/www.jornalponto.com\/site\/?p=21251"},"modified":"2025-08-29T08:51:37","modified_gmt":"2025-08-29T11:51:37","slug":"suspeito-de-assassinar-advogado-em-barra-mansa-ja-cumpriu-17-anos-de-prisao-por-crime-brutal-em-rio-claro","status":"publish","type":"post","link":"https:\/\/www.jornalponto.com\/site\/2025\/08\/29\/suspeito-de-assassinar-advogado-em-barra-mansa-ja-cumpriu-17-anos-de-prisao-por-crime-brutal-em-rio-claro\/","title":{"rendered":"Suspeito de assassinar advogado em Barra Mansa j\u00e1 cumpriu 17 anos de pris\u00e3o por crime brutal em Rio Claro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>Agiu com ajuda de comparsas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Daniel Bruno Avelar Costa, conhecido como Danielzinho ou Liel, de 43 anos, apontado como autor do homic\u00eddio do advogado H\u00e9rcules Anton de Almeida, ocorrido em 21 de outubro de 2024, no bairro Santa Rosa, em Barra Mansa, j\u00e1 possu\u00eda um hist\u00f3rico criminal marcado pela viol\u00eancia. De acordo com uma fonte da PM, anos atr\u00e1s, ele foi condenado por degolar uma mulher na cidade de Rio Claro (RJ), crime que chocou a regi\u00e3o. Pelo assassinato, cumpriu 17 anos de pris\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Nesta quinta-feira (28), ap\u00f3s investiga\u00e7\u00f5es que confirmaram seu envolvimento na morte do advogado, os policiais localizaram Daniel na Rua 1039 A, no bairro Volta Grande, em Volta Redonda, onde foi detido sem resist\u00eancia. Em seguida, ele foi conduzido \u00e0 90\u00aa DP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agiu com ajuda de comparsas Daniel Bruno Avelar Costa, conhecido como Danielzinho ou Liel, de 43 anos, apontado como autor do homic\u00eddio do advogado H\u00e9rcules Anton de Almeida, ocorrido em 21 de outubro de 2024, no bairro Santa Rosa, em Barra Mansa, j\u00e1 possu\u00eda um hist\u00f3rico criminal marcado pela viol\u00eancia. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[48,42,90],"tags":[],"class_list":["post-21251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barra-do-pirai","category-rio-claro","category-sacode-policia"],"_links":{"self":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/21251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/comments?post=21251"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/21251\/revisions"}],"predecessor-version":[{"id":21252,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/21251\/revisions\/21252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/media\/21199"}],"wp:attachment":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/media?parent=21251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/categories?post=21251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/tags?post=21251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}