{"id":4853,"date":"2023-02-14T16:36:00","date_gmt":"2023-02-14T19:36:00","guid":{"rendered":"https:\/\/www.jornalponto.com\/?p=4853"},"modified":"2023-02-14T15:58:08","modified_gmt":"2023-02-14T18:58:08","slug":"itatiaia-promove-carnazumba-nesta-quarta-feira-15","status":"publish","type":"post","link":"https:\/\/www.jornalponto.com\/site\/2023\/02\/14\/itatiaia-promove-carnazumba-nesta-quarta-feira-15\/","title":{"rendered":"Itatiaia promove &#8216;Carnazumba&#8217; nesta quarta-feira, 15"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-default\"><img alt=\"\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.jornalponto.com\/wp-content\/uploads\/2023\/02\/CARNAZUMBA-1024x683.jpg\" alt=\"\" class=\"wp-image-4833\" srcset=\"https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2023\/02\/CARNAZUMBA-1024x683.jpg 1024w, https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2023\/02\/CARNAZUMBA-300x200.jpg 300w, https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2023\/02\/CARNAZUMBA-768x512.jpg 768w, https:\/\/www.jornalponto.com\/site\/wp-content\/uploads\/2023\/02\/CARNAZUMBA.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nesta quarta-feira, dia 15, acontece o 1\u00ba Carnazumba, o pr\u00e9-carnaval do projeto de Zumba, que ser\u00e1 realizado em comemora\u00e7\u00e3o a festa mais popular do planeta. O evento, organizado pela Secretaria de Esporte e Lazer, ser\u00e1 realizado das 18h \u00e0s 22h, no Gin\u00e1sio Poliesportivo Raphael Quintino da Fonseca, na Avenida Tr\u00eas, no bairro Jardim Itatiaia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A expectativa \u00e9 que cerca de 70 pessoas compare\u00e7am a atividade, que contar\u00e1 sucessos de 2023, marchinhas carnavalescas e um ambiente decorado e colorido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a professora do Projeto Zumba, Adriana Leal, o evento \u00e9 aberto para o p\u00fablico em geral e quem quiser poder vestir uma fantasia e reunir toda a fam\u00edlia para participar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013&nbsp;&nbsp;Convido todos para participarem do Carnazumba, uma aula super especial de carnaval que vai acontecer nesta quarta-feira, a partir das 18 horas, na quadra do bairro Jardim Itatiaia. Ser\u00e1 uma aul\u00e3o bastante animado. Coloquem suas fantasias e venham curtir conosco \u2013 convidou a professora do projeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Zumba \u00e9 uma atividade f\u00edsica aer\u00f3bica tradicional que apresenta movimentos de dan\u00e7a e coreografias, fazendo a mistura de v\u00e1rios ritmos latinos e internacionais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira, dia 15, acontece o 1\u00ba Carnazumba, o pr\u00e9-carnaval do projeto de Zumba, que ser\u00e1 realizado em comemora\u00e7\u00e3o a festa mais popular do planeta. O evento, organizado pela Secretaria de Esporte e Lazer, ser\u00e1 realizado das 18h \u00e0s 22h, no Gin\u00e1sio Poliesportivo Raphael Quintino da Fonseca, na Avenida Tr\u00eas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4833,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[69,43,72],"tags":[],"class_list":["post-4853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-itatiaia","category-ultimas"],"_links":{"self":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/4853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/comments?post=4853"}],"version-history":[{"count":1,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/4853\/revisions"}],"predecessor-version":[{"id":4854,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/posts\/4853\/revisions\/4854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/media\/4833"}],"wp:attachment":[{"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/media?parent=4853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/categories?post=4853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalponto.com\/site\/wp-json\/wp\/v2\/tags?post=4853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}